{"id":1545,"date":"2022-04-01T17:07:00","date_gmt":"2022-04-01T15:07:00","guid":{"rendered":"https:\/\/shibianta.com\/die-trickster-figur-und-der-geist-als-trickster\/"},"modified":"2022-04-04T12:22:59","modified_gmt":"2022-04-04T10:22:59","slug":"die-trickster-figur-und-der-geist-als-trickster","status":"publish","type":"post","link":"https:\/\/shibianta.com\/de\/die-trickster-figur-und-der-geist-als-trickster\/","title":{"rendered":"Die Trickster-Figur und der Geist als ein Trickster"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/Isis.jpeg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"807\" src=\"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/Isis-1024x807.jpeg\" alt=\"\" class=\"wp-image-1534\" srcset=\"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/Isis-1024x807.jpeg 1024w, https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/Isis-300x237.jpeg 300w, https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/Isis-768x606.jpeg 768w, https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/Isis.jpeg 1400w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><figcaption>G\u00f6ttin Isis<\/figcaption><\/figure><\/div>\n\n<h2 class=\"wp-block-heading\">1. April Extra\/ Sonderausgabe &#8211; Trickster<\/h2>\n\n<p class=\"has-medium-font-size\">Ich war am &#8220;verlieren meines Verstandes&#8221; heute Morgen w\u00e4hrend der Ashtanga-Yoga-Praxis: Die rasanten Gedanken wirbelten herum und mein Verstand schien mir Streiche zu spielen. W\u00e4hrend ich \u00fcber die Tricksereien meines Verstandes gr\u00fcbelte, kam mir eine interessante Einsicht: Es gibt eine intrinsische und paradoxe Verbindung zwischen der Tricksterfigur und dem Verstand. <\/p>\n\n<!--more-->\n\n<p class=\"has-medium-font-size\">Der Trickster ist auf der Welt unter vielen Namen bekannt. Sie ist ein kultur\u00fcbergreifender Archetyp, bekannt als der Yoruba-Trickstergott Eshu, die \u00e4gyptische G\u00f6ttin Isis, der Akan Anansi, Loki der nordischen Mythologie, die japanischen Kitsune, der Heyoka der Sioux, der griechische Hermes, der r\u00f6mische Merkur, der Narr im Tarot, die Schlange und Eva in der Bibelgeschichte usw. <\/p>\n\n<p class=\"has-medium-font-size\">Die Tricksterfigur ist bekannt f\u00fcr ihren brillanten Verstand, ihre Gerissenheit, ihre Kreativit\u00e4t, ihren Witz, ihre F\u00e4higkeit, Chancen in scheinbar aussichtslosen Situationen zu sehen, und die Geschicktheit, ihre scheinbaren Schw\u00e4chen in Tugenden umzuwandeln. Sie wird mit Kreuzungen, Kommunikation, Reisen, Magie und Gastaltwandlung in Verbindung gebracht. Sie \u00fcberlistet die m\u00e4chtigsten G\u00f6tter, passt sich geschickt an und formt ihre Gestalt den Umst\u00e4nden entsprechend. Sie besitzt die Macht der Transformation und kennt das Gesetz des Nicht-Seins. Die Tricksterfigur ist weder dies noch das, sondern alles und nichts gleichzeitig. Diese Qualit\u00e4ten macht sie zu einem wunderbaren Kandidaten f\u00fcr queere Menschen, die auf sie gut zur\u00fcckgreifen k\u00f6nnen. Sie ist das Beispiel eines kulturellen Gender unspezifischen und nicht-bin\u00e4ren Archetyps.<\/p>\n\n<h2 class=\"wp-block-heading\">Die Verbindung zwischen dem Verstand und der Tricksterfigur<\/h2>\n\n<p class=\"has-medium-font-size\">In der Astrologie ist Merkur der Planet, der mit dem Geist und dem Denken verbunden ist. Es ist der einzige Planet, dem in der traditionellen hellenistischen Astrologie kein Geschlecht zugeordnet ist. Im Tarot entspricht der Narr der Zahl Null. Die gro\u00dfe 0, die alles einschlie\u00dft und nichts enth\u00e4lt, die unendliche M\u00f6glichkeit, aus der alle Zahlen hervorgehen. In der Bibel trickst die Schlange Eva aus, die ihrerseits Adam dazu verf\u00fchrt, von der Frucht des Wissens zu essen. In der \u00e4gyptischen Mythologie bringt die G\u00f6ttin Isis den Sonnengott Re dazu, seinen \u00e4u\u00dferst m\u00e4chtigen geheimen Namen zu verraten, und so geht es weiter und weiter. <\/p>\n\n<p class=\"has-medium-font-size\">Wir k\u00f6nnen die Tricksterfigur als jemanden sehen, die die Qualit\u00e4ten der Intelligenz tr\u00e4gt. Wir k\u00f6nnen diesen Charakter aber auch als Archetyp des Geistes verstehen. Aus diesem Blickwinkel wird der Geist zum Trickster. Und ist der Geist nicht wirklich der Gestaltwandler schlechthin? Er hat keine Materie und daher keine k\u00f6rperlichen Begrenzungen, er kann Gedanken erschaffen, brechen, formen, anpassen, er kann ein Objekt definieren und umdefinieren, er kann zu fernen L\u00e4ndern reichen, er kann Bekanntes und Unbekanntes ergr\u00fcnden und er kann uns austricksen.<\/p>\n\n<h2 class=\"wp-block-heading\">Der Geist als ein Trickster <\/h2>\n\n<p class=\"has-medium-font-size\">Wenn wir den Geist als des Narrens Null und als den geschlechtsneutralen Merkur bezeichnen, erkennen wir seine nicht-bin\u00e4re Qualit\u00e4t an. Interessanterweise ist er jedoch gleichzeitig genau jene Kraft, der das Bin\u00e4re erschaffen hat. In Gender- und Queer-Diskursen sprechen wir \u00fcber Sex und Gender-Fluidit\u00e4t und \u00fcber die Binarit\u00e4t von m\u00e4nnlich und weiblich als konzeptionelles Produkt des Geistes. Wie <a href=\"https:\/\/selforganizedseminar.files.wordpress.com\/2011\/07\/butler-gender_trouble.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Judith Butler<\/a> es ausdr\u00fcckte, wird das Geschlecht durch Iterationen erschaffen: Sich im Laufe der Geschichte oft genug wiederholende kulturelle Inszenierungen, bis sie sich in Form und Gestalt manifestieren.<\/p>\n\n<p class=\"has-medium-font-size\">Wenn wir dem Argument folgen und den Geist als die Ursache von dem Bin\u00e4ren und der Dualit\u00e4t sehen, kommen wir zu einem Paradoxon. Es scheint, dass genau das, was nicht-dual ist, die Ursache der Dualit\u00e4t ist. Ich bin jedes Mal \u00fcberw\u00e4ltigt von der Paradoxie des Universums. Ich liebe es. Universum, du bist zweifellos der gr\u00f6\u00dfte Trickster. <\/p>\n\n<p class=\"has-medium-font-size\">Fazit: Wir haben gute Neuigkeiten! Wenn der Verstand Dualit\u00e4t erschafft und gleichzeitig ein hinterh\u00e4ltiger gestaltenwandelnder Trickster ist, scheint es, dass er \u00fcber das Heilmittel gegen sein eigenes Konstrukt verf\u00fcgt <\/p>\n\n<p class=\"has-medium-font-size\">Passt aufeinander auf und genie\u00dft eure gestalten-wandelnde Fluidit\u00e4t,<\/p>\n\n<p class=\"has-medium-font-size\">Mit Liebe<\/p>\n\n<p class=\"has-medium-font-size\">&lt;3<\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1. April Extra\/ Sonderausgabe &#8211; Trickster Ich war am &#8220;verlieren meines Verstandes&#8221; heute Morgen w\u00e4hrend der Ashtanga-Yoga-Praxis: Die rasanten Gedanken wirbelten herum und mein Verstand schien mir Streiche zu spielen. W\u00e4hrend ich \u00fcber die Tricksereien meines Verstandes gr\u00fcbelte, kam mir eine interessante Einsicht: Es gibt eine intrinsische und paradoxe Verbindung zwischen der Tricksterfigur und dem &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/shibianta.com\/de\/die-trickster-figur-und-der-geist-als-trickster\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eDie Trickster-Figur und der Geist als ein Trickster\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1545","post","type-post","status-publish","format-standard","hentry","category-einsichten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Trickster-Figur und der Geist als ein Trickster &#8211; Shibianta<\/title>\n<meta name=\"description\" content=\"Die Trickster-Figur als Gender unspezifische, formwandelnde kultur\u00fcbergreifende mythische Figur und der Geist als ein Trickster.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shibianta.com\/de\/?p=1545\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Trickster-Figur und der Geist als ein Trickster &#8211; Shibianta\" \/>\n<meta property=\"og:description\" content=\"Die Trickster-Figur als Gender unspezifische, formwandelnde kultur\u00fcbergreifende mythische Figur und der Geist als ein Trickster.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shibianta.com\/de\/?p=1545\" \/>\n<meta property=\"og:site_name\" content=\"Shibianta\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-01T15:07:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-04T10:22:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/Isis-1024x807.jpeg\" \/>\n<meta name=\"author\" content=\"antadzea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"antadzea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/?p=1545#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/?p=1545\"},\"author\":{\"name\":\"antadzea\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/#\\\/schema\\\/person\\\/5f8f854826cc7febd7375923755f88ff\"},\"headline\":\"Die Trickster-Figur und der Geist als ein Trickster\",\"datePublished\":\"2022-04-01T15:07:00+00:00\",\"dateModified\":\"2022-04-04T10:22:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/?p=1545\"},\"wordCount\":660,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/?p=1545#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shibianta.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Isis-1024x807.jpeg\",\"articleSection\":[\"Einsichten\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/shibianta.com\\\/de\\\/?p=1545#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/?p=1545\",\"url\":\"https:\\\/\\\/shibianta.com\\\/de\\\/?p=1545\",\"name\":\"Die Trickster-Figur und der Geist als ein Trickster &#8211; Shibianta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/?p=1545#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/?p=1545#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shibianta.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Isis-1024x807.jpeg\",\"datePublished\":\"2022-04-01T15:07:00+00:00\",\"dateModified\":\"2022-04-04T10:22:59+00:00\",\"description\":\"Die Trickster-Figur als Gender unspezifische, formwandelnde kultur\u00fcbergreifende mythische Figur und der Geist als ein Trickster.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/?p=1545#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shibianta.com\\\/de\\\/?p=1545\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/?p=1545#primaryimage\",\"url\":\"https:\\\/\\\/shibianta.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Isis-1024x807.jpeg\",\"contentUrl\":\"https:\\\/\\\/shibianta.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Isis-1024x807.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/?p=1545#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/shibianta.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Trickster-Figur und der Geist als ein Trickster\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/#website\",\"url\":\"https:\\\/\\\/shibianta.com\\\/\",\"name\":\"Shibianta\",\"description\":\"Archaische Br\u00fccke der Heilung\",\"publisher\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shibianta.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/#organization\",\"name\":\"Shibianta\",\"url\":\"https:\\\/\\\/shibianta.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shibianta.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/sicocxlis_xe_250-removebg-preview-1.png\",\"contentUrl\":\"https:\\\/\\\/shibianta.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/sicocxlis_xe_250-removebg-preview-1.png\",\"width\":250,\"height\":250,\"caption\":\"Shibianta\"},\"image\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/#\\\/schema\\\/person\\\/5f8f854826cc7febd7375923755f88ff\",\"name\":\"antadzea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac44ee02bf3ebf9700a0af53349777cf906e4d67a952042b28874d309318e864?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac44ee02bf3ebf9700a0af53349777cf906e4d67a952042b28874d309318e864?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac44ee02bf3ebf9700a0af53349777cf906e4d67a952042b28874d309318e864?s=96&d=blank&r=g\",\"caption\":\"antadzea\"},\"url\":\"https:\\\/\\\/shibianta.com\\\/de\\\/author\\\/antadzea\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Trickster-Figur und der Geist als ein Trickster &#8211; Shibianta","description":"Die Trickster-Figur als Gender unspezifische, formwandelnde kultur\u00fcbergreifende mythische Figur und der Geist als ein Trickster.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shibianta.com\/de\/?p=1545","og_locale":"de_DE","og_type":"article","og_title":"Die Trickster-Figur und der Geist als ein Trickster &#8211; Shibianta","og_description":"Die Trickster-Figur als Gender unspezifische, formwandelnde kultur\u00fcbergreifende mythische Figur und der Geist als ein Trickster.","og_url":"https:\/\/shibianta.com\/de\/?p=1545","og_site_name":"Shibianta","article_published_time":"2022-04-01T15:07:00+00:00","article_modified_time":"2022-04-04T10:22:59+00:00","og_image":[{"url":"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/Isis-1024x807.jpeg","type":"","width":"","height":""}],"author":"antadzea","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"antadzea","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/shibianta.com\/de\/?p=1545#article","isPartOf":{"@id":"https:\/\/shibianta.com\/de\/?p=1545"},"author":{"name":"antadzea","@id":"https:\/\/shibianta.com\/#\/schema\/person\/5f8f854826cc7febd7375923755f88ff"},"headline":"Die Trickster-Figur und der Geist als ein Trickster","datePublished":"2022-04-01T15:07:00+00:00","dateModified":"2022-04-04T10:22:59+00:00","mainEntityOfPage":{"@id":"https:\/\/shibianta.com\/de\/?p=1545"},"wordCount":660,"commentCount":0,"publisher":{"@id":"https:\/\/shibianta.com\/#organization"},"image":{"@id":"https:\/\/shibianta.com\/de\/?p=1545#primaryimage"},"thumbnailUrl":"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/Isis-1024x807.jpeg","articleSection":["Einsichten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/shibianta.com\/de\/?p=1545#respond"]}]},{"@type":"WebPage","@id":"https:\/\/shibianta.com\/de\/?p=1545","url":"https:\/\/shibianta.com\/de\/?p=1545","name":"Die Trickster-Figur und der Geist als ein Trickster &#8211; Shibianta","isPartOf":{"@id":"https:\/\/shibianta.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shibianta.com\/de\/?p=1545#primaryimage"},"image":{"@id":"https:\/\/shibianta.com\/de\/?p=1545#primaryimage"},"thumbnailUrl":"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/Isis-1024x807.jpeg","datePublished":"2022-04-01T15:07:00+00:00","dateModified":"2022-04-04T10:22:59+00:00","description":"Die Trickster-Figur als Gender unspezifische, formwandelnde kultur\u00fcbergreifende mythische Figur und der Geist als ein Trickster.","breadcrumb":{"@id":"https:\/\/shibianta.com\/de\/?p=1545#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shibianta.com\/de\/?p=1545"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/shibianta.com\/de\/?p=1545#primaryimage","url":"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/Isis-1024x807.jpeg","contentUrl":"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/Isis-1024x807.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/shibianta.com\/de\/?p=1545#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shibianta.com\/de\/"},{"@type":"ListItem","position":2,"name":"Die Trickster-Figur und der Geist als ein Trickster"}]},{"@type":"WebSite","@id":"https:\/\/shibianta.com\/#website","url":"https:\/\/shibianta.com\/","name":"Shibianta","description":"Archaische Br\u00fccke der Heilung","publisher":{"@id":"https:\/\/shibianta.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shibianta.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/shibianta.com\/#organization","name":"Shibianta","url":"https:\/\/shibianta.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/shibianta.com\/#\/schema\/logo\/image\/","url":"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/01\/sicocxlis_xe_250-removebg-preview-1.png","contentUrl":"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/01\/sicocxlis_xe_250-removebg-preview-1.png","width":250,"height":250,"caption":"Shibianta"},"image":{"@id":"https:\/\/shibianta.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/shibianta.com\/#\/schema\/person\/5f8f854826cc7febd7375923755f88ff","name":"antadzea","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ac44ee02bf3ebf9700a0af53349777cf906e4d67a952042b28874d309318e864?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ac44ee02bf3ebf9700a0af53349777cf906e4d67a952042b28874d309318e864?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac44ee02bf3ebf9700a0af53349777cf906e4d67a952042b28874d309318e864?s=96&d=blank&r=g","caption":"antadzea"},"url":"https:\/\/shibianta.com\/de\/author\/antadzea\/"}]}},"_links":{"self":[{"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/posts\/1545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/comments?post=1545"}],"version-history":[{"count":5,"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/posts\/1545\/revisions"}],"predecessor-version":[{"id":1594,"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/posts\/1545\/revisions\/1594"}],"wp:attachment":[{"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/media?parent=1545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/categories?post=1545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/tags?post=1545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}