{"id":1773,"date":"2022-04-29T20:35:00","date_gmt":"2022-04-29T18:35:00","guid":{"rendered":"https:\/\/shibianta.com\/?p=1773"},"modified":"2022-05-01T12:31:05","modified_gmt":"2022-05-01T10:31:05","slug":"altes-loslassen","status":"publish","type":"post","link":"https:\/\/shibianta.com\/de\/altes-loslassen\/","title":{"rendered":"Altes loslassen"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/EDO_six-of-swords_rue-1.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/EDO_six-of-swords_rue-1-760x1024.jpg\" alt=\"\" class=\"wp-image-1756\" width=\"380\" height=\"512\" srcset=\"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/EDO_six-of-swords_rue-1-760x1024.jpg 760w, https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/EDO_six-of-swords_rue-1-223x300.jpg 223w, https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/EDO_six-of-swords_rue-1-768x1035.jpg 768w, https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/EDO_six-of-swords_rue-1.jpg 1000w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/><\/a><figcaption>Six of Swords von Kevin Jay Stanton<\/figcaption><\/figure><\/div>\n\n<p class=\"has-medium-font-size\">Warum ist es so schwer, das Alte hinter sich zu lassen, auch wenn wir wissen, dass wir zum Besseren aufbrechen? Auch wenn wir wissen, dass der Weg, der uns ruft, derjenige ist, f\u00fcr den wir die ganze Zeit gebetet haben. Endlich wurden wir erh\u00f6rt. Hier ist es, gleich um die Ecke. Die Zeit ist gekommen. Wir k\u00f6nnen um die Ecke gehen, in dem Wissen, dass der Weg hinter uns wie Sandh\u00fcgel im Wind verschwinden wird. <\/p>\n\n<!--more-->\n\n<p class=\"has-medium-font-size\">Wir wissen das Und dennoch tut es weh. Warum ist es so schwer, das loszulassen, was uns Schmerzen gebracht hat? Vielleicht, weil kostbare Momente in schmerzhafte geschmolzen sind und uns glauben machen, dass die Sch\u00f6nheit der Rose nur dann zu sehen ist, wenn wir inmitten von Dornenb\u00fcschen stehen? Werden unsere gr\u00fcnen Freunde, die Zeugen und Ratgeber unserer Sorgen, uns weiterhin zum Trost kommen? Die beruhigende Ber\u00fchrung bemooster B\u00e4ume nach einer schlaflosen Nacht, das Streicheln des Windes auf nassen Wangen, der hoffnungsgebender Blick bunter Blumen, die uns an die vielf\u00e4ltigen M\u00f6glichkeiten des Lebens erinnern. Meine Psyche verbindet die Smaragdmomente des Lebens mit den wunden Dornenspuren. Als ob ich die Sch\u00f6nheit der Rose nur dann genie\u00dfen k\u00f6nnte, wenn ich fest in ihren Stiel greife. Lass los, Liebe, h\u00f6re ich. Es ist Zeit, fl\u00fcstern mir meine Vorfahren zu. <\/p>\n\n<p class=\"has-medium-font-size\">Welch ein Leben, das Leben. Segel vorw\u00e4rts. Weiter vorw\u00e4rts. Lass uns weiter gehen. Die B\u00e4ume rufen. Geh in den Wald. Der Wald ist keine Rose, der Wald kein Dorn, der Wald ist nicht dies, der Wald ist nicht das. Der Wald ist mehr als das. Ein sich st\u00e4ndig entfaltendes Passieren. Bl\u00e4tter sch\u00fcttelnde Winde, Moose befeuchtende Regentropfen, mit V\u00f6geln tanzende B\u00e4ume, zu Nachbarn reichende Blumen, mit Genossen zu Abend essende Mikroben, auf atmenden K\u00f6rpern reisende K\u00e4fer, im Licht auftauchende Farben, durch Schatten fallende Sonnenstrahlen, sich auf dem Nacken stellende Haare, in einem Orchester von Herzschl\u00e4gen schlagendes Herz. <\/p>\n\n<p class=\"has-medium-font-size\">M\u00f6gen uns die Winde mit einem kleinen Mutes-Schubs befl\u00fcgeln, f\u00fcr unseren Weg voraus,<\/p>\n\n<p class=\"has-medium-font-size\">Liebe &lt;3<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Warum ist es so schwer, das Alte hinter sich zu lassen, auch wenn wir wissen, dass wir zum Besseren aufbrechen? Auch wenn wir wissen, dass der Weg, der uns ruft, derjenige ist, f\u00fcr den wir die ganze Zeit gebetet haben. Endlich wurden wir erh\u00f6rt. Hier ist es, gleich um die Ecke. Die Zeit ist gekommen. &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/shibianta.com\/de\/altes-loslassen\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eAltes loslassen\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[45,40,51],"tags":[],"class_list":["post-1773","post","type-post","status-publish","format-standard","hentry","category-animistische-eintrage-de","category-gedanken-gefuhle","category-hinter-den-kulissen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Altes loslassen &#8211; Shibianta<\/title>\n<meta name=\"description\" content=\"Warum ist es so schwer, das Alte hinter sich zu lassen, auch wenn wir wissen, dass wir zum Besseren aufbrechen? Gedanken zu \u00dcbergangserfahrungen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shibianta.com\/de\/altes-loslassen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Altes loslassen &#8211; Shibianta\" \/>\n<meta property=\"og:description\" content=\"Warum ist es so schwer, das Alte hinter sich zu lassen, auch wenn wir wissen, dass wir zum Besseren aufbrechen? Gedanken zu \u00dcbergangserfahrungen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shibianta.com\/de\/altes-loslassen\/\" \/>\n<meta property=\"og:site_name\" content=\"Shibianta\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-29T18:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-01T10:31:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/EDO_six-of-swords_rue-1-760x1024.jpg\" \/>\n<meta name=\"author\" content=\"antadzea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"antadzea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/altes-loslassen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/altes-loslassen\\\/\"},\"author\":{\"name\":\"antadzea\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/#\\\/schema\\\/person\\\/5f8f854826cc7febd7375923755f88ff\"},\"headline\":\"Altes loslassen\",\"datePublished\":\"2022-04-29T18:35:00+00:00\",\"dateModified\":\"2022-05-01T10:31:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/altes-loslassen\\\/\"},\"wordCount\":360,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/altes-loslassen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shibianta.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/EDO_six-of-swords_rue-1-760x1024.jpg\",\"articleSection\":[\"Animistische Eintr\u00e4ge\",\"Gedanken und Gef\u00fchle\",\"Hinter den Kulissen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/shibianta.com\\\/de\\\/altes-loslassen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/altes-loslassen\\\/\",\"url\":\"https:\\\/\\\/shibianta.com\\\/de\\\/altes-loslassen\\\/\",\"name\":\"Altes loslassen &#8211; Shibianta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/altes-loslassen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/altes-loslassen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shibianta.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/EDO_six-of-swords_rue-1-760x1024.jpg\",\"datePublished\":\"2022-04-29T18:35:00+00:00\",\"dateModified\":\"2022-05-01T10:31:05+00:00\",\"description\":\"Warum ist es so schwer, das Alte hinter sich zu lassen, auch wenn wir wissen, dass wir zum Besseren aufbrechen? Gedanken zu \u00dcbergangserfahrungen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/altes-loslassen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shibianta.com\\\/de\\\/altes-loslassen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/altes-loslassen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shibianta.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/EDO_six-of-swords_rue-1-760x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/shibianta.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/EDO_six-of-swords_rue-1-760x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/de\\\/altes-loslassen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/shibianta.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Altes loslassen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/#website\",\"url\":\"https:\\\/\\\/shibianta.com\\\/\",\"name\":\"Shibianta\",\"description\":\"Archaische Br\u00fccke der Heilung\",\"publisher\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shibianta.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/#organization\",\"name\":\"Shibianta\",\"url\":\"https:\\\/\\\/shibianta.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shibianta.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/sicocxlis_xe_250-removebg-preview-1.png\",\"contentUrl\":\"https:\\\/\\\/shibianta.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/sicocxlis_xe_250-removebg-preview-1.png\",\"width\":250,\"height\":250,\"caption\":\"Shibianta\"},\"image\":{\"@id\":\"https:\\\/\\\/shibianta.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/shibianta.com\\\/#\\\/schema\\\/person\\\/5f8f854826cc7febd7375923755f88ff\",\"name\":\"antadzea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac44ee02bf3ebf9700a0af53349777cf906e4d67a952042b28874d309318e864?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac44ee02bf3ebf9700a0af53349777cf906e4d67a952042b28874d309318e864?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac44ee02bf3ebf9700a0af53349777cf906e4d67a952042b28874d309318e864?s=96&d=blank&r=g\",\"caption\":\"antadzea\"},\"url\":\"https:\\\/\\\/shibianta.com\\\/de\\\/author\\\/antadzea\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Altes loslassen &#8211; Shibianta","description":"Warum ist es so schwer, das Alte hinter sich zu lassen, auch wenn wir wissen, dass wir zum Besseren aufbrechen? Gedanken zu \u00dcbergangserfahrungen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shibianta.com\/de\/altes-loslassen\/","og_locale":"de_DE","og_type":"article","og_title":"Altes loslassen &#8211; Shibianta","og_description":"Warum ist es so schwer, das Alte hinter sich zu lassen, auch wenn wir wissen, dass wir zum Besseren aufbrechen? Gedanken zu \u00dcbergangserfahrungen.","og_url":"https:\/\/shibianta.com\/de\/altes-loslassen\/","og_site_name":"Shibianta","article_published_time":"2022-04-29T18:35:00+00:00","article_modified_time":"2022-05-01T10:31:05+00:00","og_image":[{"url":"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/EDO_six-of-swords_rue-1-760x1024.jpg","type":"","width":"","height":""}],"author":"antadzea","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"antadzea","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/shibianta.com\/de\/altes-loslassen\/#article","isPartOf":{"@id":"https:\/\/shibianta.com\/de\/altes-loslassen\/"},"author":{"name":"antadzea","@id":"https:\/\/shibianta.com\/#\/schema\/person\/5f8f854826cc7febd7375923755f88ff"},"headline":"Altes loslassen","datePublished":"2022-04-29T18:35:00+00:00","dateModified":"2022-05-01T10:31:05+00:00","mainEntityOfPage":{"@id":"https:\/\/shibianta.com\/de\/altes-loslassen\/"},"wordCount":360,"commentCount":0,"publisher":{"@id":"https:\/\/shibianta.com\/#organization"},"image":{"@id":"https:\/\/shibianta.com\/de\/altes-loslassen\/#primaryimage"},"thumbnailUrl":"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/EDO_six-of-swords_rue-1-760x1024.jpg","articleSection":["Animistische Eintr\u00e4ge","Gedanken und Gef\u00fchle","Hinter den Kulissen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/shibianta.com\/de\/altes-loslassen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/shibianta.com\/de\/altes-loslassen\/","url":"https:\/\/shibianta.com\/de\/altes-loslassen\/","name":"Altes loslassen &#8211; Shibianta","isPartOf":{"@id":"https:\/\/shibianta.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shibianta.com\/de\/altes-loslassen\/#primaryimage"},"image":{"@id":"https:\/\/shibianta.com\/de\/altes-loslassen\/#primaryimage"},"thumbnailUrl":"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/EDO_six-of-swords_rue-1-760x1024.jpg","datePublished":"2022-04-29T18:35:00+00:00","dateModified":"2022-05-01T10:31:05+00:00","description":"Warum ist es so schwer, das Alte hinter sich zu lassen, auch wenn wir wissen, dass wir zum Besseren aufbrechen? Gedanken zu \u00dcbergangserfahrungen.","breadcrumb":{"@id":"https:\/\/shibianta.com\/de\/altes-loslassen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shibianta.com\/de\/altes-loslassen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/shibianta.com\/de\/altes-loslassen\/#primaryimage","url":"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/EDO_six-of-swords_rue-1-760x1024.jpg","contentUrl":"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/04\/EDO_six-of-swords_rue-1-760x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/shibianta.com\/de\/altes-loslassen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shibianta.com\/de\/"},{"@type":"ListItem","position":2,"name":"Altes loslassen"}]},{"@type":"WebSite","@id":"https:\/\/shibianta.com\/#website","url":"https:\/\/shibianta.com\/","name":"Shibianta","description":"Archaische Br\u00fccke der Heilung","publisher":{"@id":"https:\/\/shibianta.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shibianta.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/shibianta.com\/#organization","name":"Shibianta","url":"https:\/\/shibianta.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/shibianta.com\/#\/schema\/logo\/image\/","url":"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/01\/sicocxlis_xe_250-removebg-preview-1.png","contentUrl":"https:\/\/shibianta.com\/wp-content\/uploads\/2022\/01\/sicocxlis_xe_250-removebg-preview-1.png","width":250,"height":250,"caption":"Shibianta"},"image":{"@id":"https:\/\/shibianta.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/shibianta.com\/#\/schema\/person\/5f8f854826cc7febd7375923755f88ff","name":"antadzea","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ac44ee02bf3ebf9700a0af53349777cf906e4d67a952042b28874d309318e864?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ac44ee02bf3ebf9700a0af53349777cf906e4d67a952042b28874d309318e864?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac44ee02bf3ebf9700a0af53349777cf906e4d67a952042b28874d309318e864?s=96&d=blank&r=g","caption":"antadzea"},"url":"https:\/\/shibianta.com\/de\/author\/antadzea\/"}]}},"_links":{"self":[{"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/posts\/1773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/comments?post=1773"}],"version-history":[{"count":5,"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/posts\/1773\/revisions"}],"predecessor-version":[{"id":1789,"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/posts\/1773\/revisions\/1789"}],"wp:attachment":[{"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/media?parent=1773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/categories?post=1773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/shibianta.com\/de\/wp-json\/wp\/v2\/tags?post=1773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}